{"id":1250,"count":13,"description":"","link":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/","name":"Coffee","slug":"coffee","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coffee Archives - Coffee People<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coffee Archives - Coffee People\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/\" \/>\n<meta property=\"og:site_name\" content=\"Coffee People\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/\",\"url\":\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/\",\"name\":\"Coffee Archives - Coffee People\",\"isPartOf\":{\"@id\":\"https:\/\/coffeepeople.ee\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/coffeepeople.ee\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coffee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coffeepeople.ee\/#website\",\"url\":\"https:\/\/coffeepeople.ee\/\",\"name\":\"Coffee People\",\"description\":\"Kas usud, et maailma parimat kohvi tehakse Eestis?\",\"publisher\":{\"@id\":\"https:\/\/coffeepeople.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coffeepeople.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/coffeepeople.ee\/#organization\",\"name\":\"Coffee People\",\"url\":\"https:\/\/coffeepeople.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/coffeepeople.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/coffeepeople.ee\/wp-content\/uploads\/2021\/06\/coffee-people-logo.png\",\"contentUrl\":\"https:\/\/coffeepeople.ee\/wp-content\/uploads\/2021\/06\/coffee-people-logo.png\",\"width\":188,\"height\":63,\"caption\":\"Coffee People\"},\"image\":{\"@id\":\"https:\/\/coffeepeople.ee\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coffee Archives - Coffee People","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/","og_locale":"en_US","og_type":"article","og_title":"Coffee Archives - Coffee People","og_url":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/","og_site_name":"Coffee People","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/","url":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/","name":"Coffee Archives - Coffee People","isPartOf":{"@id":"https:\/\/coffeepeople.ee\/#website"},"breadcrumb":{"@id":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/coffeepeople.ee\/en\/product-category\/coffee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coffeepeople.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Coffee"}]},{"@type":"WebSite","@id":"https:\/\/coffeepeople.ee\/#website","url":"https:\/\/coffeepeople.ee\/","name":"Coffee People","description":"Kas usud, et maailma parimat kohvi tehakse Eestis?","publisher":{"@id":"https:\/\/coffeepeople.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coffeepeople.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/coffeepeople.ee\/#organization","name":"Coffee People","url":"https:\/\/coffeepeople.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/coffeepeople.ee\/#\/schema\/logo\/image\/","url":"https:\/\/coffeepeople.ee\/wp-content\/uploads\/2021\/06\/coffee-people-logo.png","contentUrl":"https:\/\/coffeepeople.ee\/wp-content\/uploads\/2021\/06\/coffee-people-logo.png","width":188,"height":63,"caption":"Coffee People"},"image":{"@id":"https:\/\/coffeepeople.ee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/coffeepeople.ee\/en\/wp-json\/wp\/v2\/product_cat\/1250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coffeepeople.ee\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/coffeepeople.ee\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/coffeepeople.ee\/en\/wp-json\/wp\/v2\/product?product_cat=1250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}